{"id":3010,"date":"2024-09-17T09:14:17","date_gmt":"2024-09-17T09:14:17","guid":{"rendered":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/?page_id=3010"},"modified":"2024-09-17T09:41:09","modified_gmt":"2024-09-17T09:41:09","slug":"what-is-consumer-duty","status":"publish","type":"page","link":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/","title":{"rendered":"What is consumer duty?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-3010","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What is consumer duty? - Ansvar<\/title>\n<meta name=\"description\" content=\"Read Ansvar&#039;s guide on consumer duty legislation.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is consumer duty? - Ansvar\" \/>\n<meta property=\"og:description\" content=\"Read Ansvar&#039;s guide on consumer duty legislation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/\" \/>\n<meta property=\"og:site_name\" content=\"Ansvar : Brokers\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T09:41:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/\",\"url\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/\",\"name\":\"What is consumer duty? - Ansvar\",\"isPartOf\":{\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#website\"},\"datePublished\":\"2024-09-17T09:14:17+00:00\",\"dateModified\":\"2024-09-17T09:41:09+00:00\",\"description\":\"Read Ansvar's guide on consumer duty legislation.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is consumer duty?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#website\",\"url\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/\",\"name\":\"Ansvar : Brokers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#organization\",\"name\":\"Ansvar : Brokers\",\"url\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-content\/uploads\/sites\/2\/2024\/09\/Ansvar-logo-blue.svg\",\"contentUrl\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-content\/uploads\/sites\/2\/2024\/09\/Ansvar-logo-blue.svg\",\"caption\":\"Ansvar :  Brokers\"},\"image\":{\"@id\":\"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What is consumer duty? - Ansvar","description":"Read Ansvar's guide on consumer duty legislation.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"What is consumer duty? - Ansvar","og_description":"Read Ansvar's guide on consumer duty legislation.","og_url":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/","og_site_name":"Ansvar : Brokers","article_modified_time":"2024-09-17T09:41:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/","url":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/","name":"What is consumer duty? - Ansvar","isPartOf":{"@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#website"},"datePublished":"2024-09-17T09:14:17+00:00","dateModified":"2024-09-17T09:41:09+00:00","description":"Read Ansvar's guide on consumer duty legislation.","breadcrumb":{"@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/what-is-consumer-duty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/"},{"@type":"ListItem","position":2,"name":"What is consumer duty?"}]},{"@type":"WebSite","@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#website","url":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/","name":"Ansvar : Brokers","description":"","publisher":{"@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#organization","name":"Ansvar : Brokers","url":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#\/schema\/logo\/image\/","url":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-content\/uploads\/sites\/2\/2024\/09\/Ansvar-logo-blue.svg","contentUrl":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-content\/uploads\/sites\/2\/2024\/09\/Ansvar-logo-blue.svg","caption":"Ansvar :  Brokers"},"image":{"@id":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/pages\/3010"}],"collection":[{"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/comments?post=3010"}],"version-history":[{"count":3,"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/pages\/3010\/revisions"}],"predecessor-version":[{"id":3034,"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/pages\/3010\/revisions\/3034"}],"wp:attachment":[{"href":"https:\/\/dev.ansvardevelopment.co.uk\/brokers\/wp-json\/wp\/v2\/media?parent=3010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}